{"id":4571,"date":"2025-11-26T13:35:10","date_gmt":"2025-11-26T11:35:10","guid":{"rendered":"https:\/\/itercon.com\/soluciones-proyectos\/logistic-park-banyeres\/"},"modified":"2026-06-19T11:22:29","modified_gmt":"2026-06-19T09:22:29","slug":"logistic-park-banyeres","status":"publish","type":"soluciones-proyectos","link":"https:\/\/itercon.com\/de\/losungen-und-projekte\/logistic-park-banyeres\/","title":{"rendered":"Logistic park Banyeres"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-4460 aligncenter\" src=\"https:\/\/itercon.com\/wp-content\/uploads\/2025\/11\/scanell2-800x1200.jpg\" alt=\"\" width=\"800\" height=\"1200\" srcset=\"https:\/\/itercon.com\/wp-content\/uploads\/2025\/11\/scanell2-800x1200.jpg 800w, https:\/\/itercon.com\/wp-content\/uploads\/2025\/11\/scanell2-1280x1920.jpg 1280w, https:\/\/itercon.com\/wp-content\/uploads\/2025\/11\/scanell2-768x1152.jpg 768w, https:\/\/itercon.com\/wp-content\/uploads\/2025\/11\/scanell2-1024x1536.jpg 1024w, https:\/\/itercon.com\/wp-content\/uploads\/2025\/11\/scanell2-1365x2048.jpg 1365w, https:\/\/itercon.com\/wp-content\/uploads\/2025\/11\/scanell2.jpg 1500w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; &nbsp;<\/p>\n","protected":false},"featured_media":4572,"menu_order":20,"template":"","cat-soluciones":[16],"class_list":["post-4571","soluciones-proyectos","type-soluciones-proyectos","status-publish","has-post-thumbnail","hentry","cat-soluciones-logistica"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Logistic park Banyeres - ITERCON | Grupo CYCLUS<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/itercon.com\/de\/losungen-und-projekte\/logistic-park-banyeres\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Logistic park Banyeres - ITERCON | Grupo CYCLUS\" \/>\n<meta property=\"og:description\" content=\"&nbsp; &nbsp;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/itercon.com\/de\/losungen-und-projekte\/logistic-park-banyeres\/\" \/>\n<meta property=\"og:site_name\" content=\"ITERCON | Grupo CYCLUS\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-19T09:22:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/itercon.com\/wp-content\/uploads\/2025\/11\/2025_10_30-SCANNELL-Banyeres-del-Penedes-004-e1764156947246.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1010\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/itercon.com\\\/de\\\/losungen-und-projekte\\\/logistic-park-banyeres\\\/\",\"url\":\"https:\\\/\\\/itercon.com\\\/de\\\/losungen-und-projekte\\\/logistic-park-banyeres\\\/\",\"name\":\"Logistic park Banyeres - ITERCON | Grupo CYCLUS\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/itercon.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/itercon.com\\\/de\\\/losungen-und-projekte\\\/logistic-park-banyeres\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/itercon.com\\\/de\\\/losungen-und-projekte\\\/logistic-park-banyeres\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/itercon.com\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/2025_10_30-SCANNELL-Banyeres-del-Penedes-004-e1764156947246.jpg\",\"datePublished\":\"2025-11-26T11:35:10+00:00\",\"dateModified\":\"2026-06-19T09:22:29+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/itercon.com\\\/de\\\/losungen-und-projekte\\\/logistic-park-banyeres\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/itercon.com\\\/de\\\/losungen-und-projekte\\\/logistic-park-banyeres\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/itercon.com\\\/de\\\/losungen-und-projekte\\\/logistic-park-banyeres\\\/#primaryimage\",\"url\":\"https:\\\/\\\/itercon.com\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/2025_10_30-SCANNELL-Banyeres-del-Penedes-004-e1764156947246.jpg\",\"contentUrl\":\"https:\\\/\\\/itercon.com\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/2025_10_30-SCANNELL-Banyeres-del-Penedes-004-e1764156947246.jpg\",\"width\":1920,\"height\":1010},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/itercon.com\\\/de\\\/losungen-und-projekte\\\/logistic-park-banyeres\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/itercon.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Logistic park Banyeres\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/itercon.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/itercon.com\\\/de\\\/\",\"name\":\"ITERCON\",\"description\":\"Innovaciones T\u00e9cnicas y Recursos Constructivos, S.A. empresa de Grupo Cyclus\",\"publisher\":{\"@id\":\"https:\\\/\\\/itercon.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/itercon.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/itercon.com\\\/de\\\/#organization\",\"name\":\"ITERCON\",\"url\":\"https:\\\/\\\/itercon.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/itercon.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/itercon.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/logo-itercon.png\",\"contentUrl\":\"https:\\\/\\\/itercon.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/logo-itercon.png\",\"width\":154,\"height\":40,\"caption\":\"ITERCON\"},\"image\":{\"@id\":\"https:\\\/\\\/itercon.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Logistic park Banyeres - ITERCON | Grupo CYCLUS","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/itercon.com\/de\/losungen-und-projekte\/logistic-park-banyeres\/","og_locale":"de_DE","og_type":"article","og_title":"Logistic park Banyeres - ITERCON | Grupo CYCLUS","og_description":"&nbsp; &nbsp;","og_url":"https:\/\/itercon.com\/de\/losungen-und-projekte\/logistic-park-banyeres\/","og_site_name":"ITERCON | Grupo CYCLUS","article_modified_time":"2026-06-19T09:22:29+00:00","og_image":[{"width":1920,"height":1010,"url":"https:\/\/itercon.com\/wp-content\/uploads\/2025\/11\/2025_10_30-SCANNELL-Banyeres-del-Penedes-004-e1764156947246.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/itercon.com\/de\/losungen-und-projekte\/logistic-park-banyeres\/","url":"https:\/\/itercon.com\/de\/losungen-und-projekte\/logistic-park-banyeres\/","name":"Logistic park Banyeres - ITERCON | Grupo CYCLUS","isPartOf":{"@id":"https:\/\/itercon.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/itercon.com\/de\/losungen-und-projekte\/logistic-park-banyeres\/#primaryimage"},"image":{"@id":"https:\/\/itercon.com\/de\/losungen-und-projekte\/logistic-park-banyeres\/#primaryimage"},"thumbnailUrl":"https:\/\/itercon.com\/wp-content\/uploads\/2025\/11\/2025_10_30-SCANNELL-Banyeres-del-Penedes-004-e1764156947246.jpg","datePublished":"2025-11-26T11:35:10+00:00","dateModified":"2026-06-19T09:22:29+00:00","breadcrumb":{"@id":"https:\/\/itercon.com\/de\/losungen-und-projekte\/logistic-park-banyeres\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/itercon.com\/de\/losungen-und-projekte\/logistic-park-banyeres\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/itercon.com\/de\/losungen-und-projekte\/logistic-park-banyeres\/#primaryimage","url":"https:\/\/itercon.com\/wp-content\/uploads\/2025\/11\/2025_10_30-SCANNELL-Banyeres-del-Penedes-004-e1764156947246.jpg","contentUrl":"https:\/\/itercon.com\/wp-content\/uploads\/2025\/11\/2025_10_30-SCANNELL-Banyeres-del-Penedes-004-e1764156947246.jpg","width":1920,"height":1010},{"@type":"BreadcrumbList","@id":"https:\/\/itercon.com\/de\/losungen-und-projekte\/logistic-park-banyeres\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/itercon.com\/de\/"},{"@type":"ListItem","position":2,"name":"Logistic park Banyeres"}]},{"@type":"WebSite","@id":"https:\/\/itercon.com\/de\/#website","url":"https:\/\/itercon.com\/de\/","name":"ITERCON","description":"Innovaciones T\u00e9cnicas y Recursos Constructivos, S.A. empresa de Grupo Cyclus","publisher":{"@id":"https:\/\/itercon.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/itercon.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/itercon.com\/de\/#organization","name":"ITERCON","url":"https:\/\/itercon.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/itercon.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/itercon.com\/wp-content\/uploads\/2023\/05\/logo-itercon.png","contentUrl":"https:\/\/itercon.com\/wp-content\/uploads\/2023\/05\/logo-itercon.png","width":154,"height":40,"caption":"ITERCON"},"image":{"@id":"https:\/\/itercon.com\/de\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/itercon.com\/de\/wp-json\/wp\/v2\/soluciones-proyectos\/4571","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/itercon.com\/de\/wp-json\/wp\/v2\/soluciones-proyectos"}],"about":[{"href":"https:\/\/itercon.com\/de\/wp-json\/wp\/v2\/types\/soluciones-proyectos"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/itercon.com\/de\/wp-json\/wp\/v2\/media\/4572"}],"wp:attachment":[{"href":"https:\/\/itercon.com\/de\/wp-json\/wp\/v2\/media?parent=4571"}],"wp:term":[{"taxonomy":"cat-soluciones","embeddable":true,"href":"https:\/\/itercon.com\/de\/wp-json\/wp\/v2\/cat-soluciones?post=4571"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}